{"id":8492,"date":"2015-10-18T01:38:44","date_gmt":"2015-10-18T07:38:44","guid":{"rendered":"http:\/\/la-uno.com\/blog\/?p=8492"},"modified":"2015-10-18T01:40:11","modified_gmt":"2015-10-18T07:40:11","slug":"youtube-gaming-ya-permite-suscripciones-de-paga-y-hacer-streaming-a-android","status":"publish","type":"post","link":"https:\/\/la-uno.com\/blog\/2015\/10\/18\/youtube-gaming-ya-permite-suscripciones-de-paga-y-hacer-streaming-a-android\/","title":{"rendered":"YouTube Gaming ya permite suscripciones de Paga y hacer streaming desde Android"},"content":{"rendered":"<p><a href=\"http:\/\/www.cultofandroid.com\/76739\/youtube-gaming-now-allows-paid-subscribers-streaming-from-android\/\"><img decoding=\"async\" class=\"size-full aligncenter\" src=\"http:\/\/la-uno.com\/blog\/wp-content\/uploads\/2015\/10\/Mobile-Capture-940x588.png\" alt=\"\" \/><\/a><\/p>\n<p>YouTube Gaming, la plataforma de streaming de videojuegos (al menos video) que lleg\u00f3 en Agosto en busca de derrocar a Twitch ahora ya hace streaming desde dispositivos Android.<span id=\"more-76739\"><\/span><\/p>\n<p>Al activar patrocinios &#8220;pagados&#8221;, Google cierra una gran ventana entre Youtube Gaming y Twitch (de Amazon) que permit\u00f1ia a los fans suscribirse a un jugador por una peque\u00f1a cantidad al a\u00f1o.<\/p>\n<p>Youtube Gaming tambien tiene una gran ventaja; mientras que twitch requiere que los jugadores atraigan cierta cantidad de viewers antes de ser aceptados como suscriptores, Google no impone una cantidad minima, asi que cualquiera puede ser soportado y aceptar dinero&#8230; eventualmente.<\/p>\n<p>Por ahora, solo los beta testers puedes tomar ventaja de esta nueva caracter\u00edstica.<\/p>\n<p>Los patrocinios pagados en Youtube Gaming cuestan $3.99 al mes a trav\u00e9s de Google Wallet para patrocinar a tus jugadores favoritos y tener sesiones exclusivas de chat con el gamer, una &#8220;estampita&#8221; cerca de su nombre permite ver a sus suscriptores de paga.<\/p>\n<p>Google no ha confirmado que cantidad\u00a0de\u00a0los pagos de los suscriptores van a ir a dar a los clientes, asi que no es seguro si es que ser\u00e1 mas que con Twitch que toma el 50% del precio de los suscriptores.<\/p>\n<p>Ademas de los patrocionios. Youtube Gaming ahora soporta la habilidad de hacer\u00a0el streaming\u00a0directamente desde Android, asi que no es necesario tener una PC o titulos de consola o comprar hardware adicional para poder hacer broadcasting desde tu celular que tanto amas.<\/p>\n<p>Streaming en Android no solo muestra tu juego, sino que tambi\u00e9n tu cara en un peque\u00f1o circulo alimentado de tu cara en la c\u00e1mara frontal. <a href=\"https:\/\/play.google.com\/store\/apps\/details?id=com.google.android.apps.youtube.gaming\">download the YouTube Gaming update from the Play Store now<\/a>.<\/p>\n<p>&nbsp;<\/p>\n<blockquote><p>YouTube Gaming now allows paid subscribers and the ability to broadcast content directly from Android devices.<\/p><\/blockquote>\n<p>Source: <em><a href=\"http:\/\/www.cultofandroid.com\/76739\/youtube-gaming-now-allows-paid-subscribers-streaming-from-android\/\">Cult of Android &#8211; YouTube Gaming allows subscribers, streaming from Android<\/a><\/em><\/p>\n<div class=\"pvc_clear\"><\/div>\n<p id=\"pvc_stats_8492\" class=\"pvc_stats all  \" data-element-id=\"8492\" style=\"\"><i class=\"pvc-stats-icon medium\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/la-uno.com\/blog\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p>\n<div class=\"pvc_clear\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>YouTube Gaming, la plataforma de streaming de videojuegos (al menos video) que lleg\u00f3 en Agosto en busca de derrocar a Twitch ahora ya hace streaming desde dispositivos Android. Al activar patrocinios &#8220;pagados&#8221;, Google cierra una gran ventana entre Youtube Gaming y Twitch (de Amazon) que permit\u00f1ia a los fans suscribirse a un jugador por una&hellip;<\/p>\n<div class=\"pvc_clear\"><\/div>\n<p id=\"pvc_stats_8492\" class=\"pvc_stats all  \" data-element-id=\"8492\" style=\"\"><i class=\"pvc-stats-icon medium\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/la-uno.com\/blog\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p>\n<div class=\"pvc_clear\"><\/div>\n","protected":false},"author":1,"featured_media":8494,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[185],"tags":[289,49],"class_list":["post-8492","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-videojuegos","tag-gaming","tag-youtube"],"a3_pvc":{"activated":true,"total_views":1185,"today_views":0},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/la-uno.com\/blog\/wp-content\/uploads\/2015\/10\/Mobile-Capture-940x588.png","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p529Uq-2cY","jetpack-related-posts":[{"id":8329,"url":"https:\/\/la-uno.com\/blog\/2015\/08\/26\/conoce-a-youtube-gaming\/","url_meta":{"origin":8492,"position":0},"title":"Conoce a Youtube Gaming","author":"marco","date":"August 26, 2015","format":false,"excerpt":"\u00a0 Youtube acaba de lanzar de forma oficial al archienemigo de Twitch: Youtube Gaming\u00a0en versiones Web, para Android y iOS. Cuando abres la app se presenta una barra de b\u00fasqueda en la parte superior con algunos canales principales y una serie de otros videos populares. \u00a0 La app tambi\u00e9n muestra\u2026","rel":"","context":"In &quot;Internet&quot;","block_context":{"text":"Internet","link":"https:\/\/la-uno.com\/blog\/category\/internet\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/la-uno.com\/blog\/wp-content\/uploads\/2015\/08\/1-home-feed.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/la-uno.com\/blog\/wp-content\/uploads\/2015\/08\/1-home-feed.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/la-uno.com\/blog\/wp-content\/uploads\/2015\/08\/1-home-feed.png?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/la-uno.com\/blog\/wp-content\/uploads\/2015\/08\/1-home-feed.png?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/la-uno.com\/blog\/wp-content\/uploads\/2015\/08\/1-home-feed.png?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":7960,"url":"https:\/\/la-uno.com\/blog\/2015\/06\/17\/gta-v-en-la-vida-real\/","url_meta":{"origin":8492,"position":1},"title":"GTA V en la vida real","author":"Uzziel","date":"June 17, 2015","format":"video","excerpt":"Parece que a los chicos de Corridor Digital les apasiona tanto esta ultima entrega de Rockstar que hasta han hecho una replica de como ser\u00eda pasear por Los Santos en la realidad, aunque no son los \u00fanicos pues basta con ir a YouTube y poner GTA Real para que nos\u2026","rel":"","context":"In &quot;Curiosidades&quot;","block_context":{"text":"Curiosidades","link":"https:\/\/la-uno.com\/blog\/category\/curiosidades\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/la-uno.com\/blog\/wp-content\/uploads\/2015\/06\/gta-real.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/la-uno.com\/blog\/wp-content\/uploads\/2015\/06\/gta-real.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/la-uno.com\/blog\/wp-content\/uploads\/2015\/06\/gta-real.png?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/la-uno.com\/blog\/wp-content\/uploads\/2015\/06\/gta-real.png?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":7466,"url":"https:\/\/la-uno.com\/blog\/2015\/03\/27\/youtube-ahora-soporta-video-4k-a-60fps\/","url_meta":{"origin":8492,"position":2},"title":"YouTube ahora soporta video 4K a 60fps","author":"marco","date":"March 27, 2015","format":"video","excerpt":"YouTube ha soportado el video 4K por al rededor de 1 a\u00f1o ya, tambi\u00e9n ha soportado el video a 60fps por unos meses en resoluciones inferiores (1080 y 720), pero por primera vez, la plataforma de video mas grande est\u00e1 soportando la combinaci\u00f3n de los dos. Videos grabados en \"Ultra\u2026","rel":"","context":"In &quot;Google&quot;","block_context":{"text":"Google","link":"https:\/\/la-uno.com\/blog\/category\/google-2\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/la-uno.com\/blog\/wp-content\/uploads\/2015\/03\/Screen-Shot-2015-03-27-at-13.45.23.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/la-uno.com\/blog\/wp-content\/uploads\/2015\/03\/Screen-Shot-2015-03-27-at-13.45.23.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/la-uno.com\/blog\/wp-content\/uploads\/2015\/03\/Screen-Shot-2015-03-27-at-13.45.23.png?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":7805,"url":"https:\/\/la-uno.com\/blog\/2015\/06\/01\/nintendo-podria-usar-android-para-su-siguiente-consola\/","url_meta":{"origin":8492,"position":3},"title":"Nintendo podria usar Android para su siguiente consola","author":"marco","date":"June 1, 2015","format":false,"excerpt":"Nintendo podr\u00eda dejar de lado su sistema operativo propietario y en lugar de el usar Android como base de su siguiente consola de juegos de acuerdo al peri\u00f3dico Japon\u00e9s\u00a0Nikkei, Kotaku. De ser cierto, esto ser\u00eda una verdadera victoria para Google mientras que para Nintendo esto ser\u00eda un incremento en sus\u2026","rel":"","context":"In &quot;Android&quot;","block_context":{"text":"Android","link":"https:\/\/la-uno.com\/blog\/category\/mobile\/android\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/la-uno.com\/blog\/wp-content\/uploads\/2015\/06\/super-mario-nintendo-statue.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/la-uno.com\/blog\/wp-content\/uploads\/2015\/06\/super-mario-nintendo-statue.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/la-uno.com\/blog\/wp-content\/uploads\/2015\/06\/super-mario-nintendo-statue.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/la-uno.com\/blog\/wp-content\/uploads\/2015\/06\/super-mario-nintendo-statue.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/la-uno.com\/blog\/wp-content\/uploads\/2015\/06\/super-mario-nintendo-statue.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":9086,"url":"https:\/\/la-uno.com\/blog\/2016\/06\/20\/el-mejor-mensajero-de-2016\/","url_meta":{"origin":8492,"position":4},"title":"El mejor mensajero de 2016","author":"marco","date":"June 20, 2016","format":false,"excerpt":"Todos los d\u00edas mandamos mensajes, todos los d\u00edas recibimos mensajes, pero ya no es como antes que solo mandabamos mensajes de texto, con una cantidad de texto limitada y utilizabamos \"emoticonos\" y palabras cortas como \"TKM\", \"DTB\" etc.. Hoy tenemos diferentes opciones para enviar mensajes de texto que ahora son\u2026","rel":"","context":"In &quot;Internet&quot;","block_context":{"text":"Internet","link":"https:\/\/la-uno.com\/blog\/category\/internet\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/la-uno.com\/blog\/wp-content\/uploads\/2016\/06\/imessage-icon-ios-7.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":5589,"url":"https:\/\/la-uno.com\/blog\/2014\/10\/13\/ventajas-del-alojamiento-web-compartido\/","url_meta":{"origin":8492,"position":5},"title":"Ventajas del alojamiento web compartido","author":"marco","date":"October 13, 2014","format":false,"excerpt":"Alojamiento web, o web hosting en ingl\u00e9s, es el servicio que provee a los usuarios de Internet el poder almacenar datos como fotos, v\u00eddeos o cualquier contenido accesible v\u00eda web, llam\u00e1ndose as\u00ed a partir del alojamiento en hoteles donde uno ocupa una habitaci\u00f3n o lugar en especifico, de ah\u00ed el\u2026","rel":"","context":"In &quot;Internet&quot;","block_context":{"text":"Internet","link":"https:\/\/la-uno.com\/blog\/category\/internet\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/la-uno.com\/blog\/wp-content\/uploads\/2014\/10\/hostingsd.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/la-uno.com\/blog\/wp-content\/uploads\/2014\/10\/hostingsd.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/la-uno.com\/blog\/wp-content\/uploads\/2014\/10\/hostingsd.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/la-uno.com\/blog\/wp-content\/uploads\/2014\/10\/hostingsd.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/la-uno.com\/blog\/wp-json\/wp\/v2\/posts\/8492","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/la-uno.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/la-uno.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/la-uno.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/la-uno.com\/blog\/wp-json\/wp\/v2\/comments?post=8492"}],"version-history":[{"count":4,"href":"https:\/\/la-uno.com\/blog\/wp-json\/wp\/v2\/posts\/8492\/revisions"}],"predecessor-version":[{"id":8497,"href":"https:\/\/la-uno.com\/blog\/wp-json\/wp\/v2\/posts\/8492\/revisions\/8497"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/la-uno.com\/blog\/wp-json\/wp\/v2\/media\/8494"}],"wp:attachment":[{"href":"https:\/\/la-uno.com\/blog\/wp-json\/wp\/v2\/media?parent=8492"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/la-uno.com\/blog\/wp-json\/wp\/v2\/categories?post=8492"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/la-uno.com\/blog\/wp-json\/wp\/v2\/tags?post=8492"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}