{"id":5680,"date":"2014-12-02T23:54:45","date_gmt":"2014-12-02T23:54:45","guid":{"rendered":"http:\/\/la-uno.com\/blog\/index.php\/2014\/12\/02\/todo-lo-que-tienes-que-saber-sobre-un-data-center\/"},"modified":"2015-02-18T14:46:15","modified_gmt":"2015-02-18T20:46:15","slug":"todo-lo-que-tienes-que-saber-sobre-un-data-center","status":"publish","type":"post","link":"https:\/\/la-uno.com\/blog\/2014\/12\/02\/todo-lo-que-tienes-que-saber-sobre-un-data-center\/","title":{"rendered":"Todo lo que tienes que saber sobre un Data Center"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter  wp-image-550\" src=\"http:\/\/la-uno.com\/blog\/wp-content\/uploads\/2014\/12\/dc.jpg\" alt=\"dc\" width=\"1037\" height=\"741\" \/><\/p>\n<h5>\u00bfAlguna vez te has preguntado a d\u00f3nde va toda esa informaci\u00f3n que guardas en la nube?, es decir, la \u201cnube\u201d es s\u00f3lo una expresi\u00f3n, la realidad es que hay un lugar f\u00edsico en el que las empresas o personas,\u00a0<strong>guardan toda la informaci\u00f3n<\/strong>\u00a0que no pueden almacenar en dispositivos.<\/h5>\n<h5>A continuaci\u00f3n, te presentamos\u00a0<strong>cinco cosas que no sabes sobre los centros de datos<\/strong>, y que, por mera curiosidad, tal vez debas saber.<\/h5>\n<h5><\/h5>\n<ol>\n<li>\n<h5><strong>Son lugares muy seguros.<\/strong>\u00a0F\u00edsicamente son lugares a los cuales no se puede tener acceso tan f\u00e1cilmente. Un centro de datos nivel cinco con certificaci\u00f3n ICREA debe tener, en aspectos generales, instalaciones el\u00e9ctricas, aire acondicionado, comunicaciones, piso elevado, c\u00e1maras de vigilancia, control de acceso, detecci\u00f3n y supresi\u00f3n de incendios. Probablemente s\u00f3lo Godzilla lo podr\u00eda destruir.<\/h5>\n<\/li>\n<li>\n<h5><strong>Tienen que ser redundantes.<\/strong>\u00a0Ante cualquier eventualidad, el centro de datos siempre tiene que operar, para que los clientes tengan acceso a su informaci\u00f3n. La redundancia debe reflejarse en todos los sentidos, por ejemplo, en alimentaci\u00f3n el\u00e9ctrica, contar con m\u00e1s de dos fuentes de energ\u00eda. En sistemas de enfriamiento, tener m\u00e1s opciones aparte del aire acondicionado, para mantener en buenas condiciones los servidores.<\/h5>\n<\/li>\n<li>\n<h5><strong>Monitoreo en tiempo real.<\/strong>\u00a0Por aquello de los ataques inform\u00e1ticos, los centros de datos deben estar preparados para vigilar las amenazas externas. Y es que el personal debe estar preparado para monitorear en tiempo real el origen y destino de los ataques en todo el mundo.<\/h5>\n<\/li>\n<li>\n<h5><strong>Son modulares.<\/strong>\u00a0Los clientes que pagan por este tipo de servicios, deben saber que los centros de datos se ajustan a sus necesidades. Pueden llevar equipo propio, rentar metros cuadrados del lugar, y en algunos casos, hasta se les proporcionan oficinas para que puedan administrar su negocio.<\/h5>\n<\/li>\n<li>\n<h5><strong>Espacios amigables con el medio ambiente.<\/strong>\u00a0Pese a lo que podr\u00eda creerse, el gasto de energ\u00eda el\u00e9ctrica es m\u00ednimo, por ejemplo, los sistemas de cogeneraci\u00f3n de energ\u00eda permiten aprovechar al m\u00e1ximo el gas natural, para ser la primera fuente de energ\u00eda que permita proveer a los sistemas el\u00e9ctricos y de enfriamiento del centro de datos.<\/h5>\n<\/li>\n<\/ol>\n<h5><\/h5>\n<h5><\/h5>\n<h5><strong>Un negocio en crecimiento<\/strong><\/h5>\n<h5>En nuestro pa\u00eds <strong>el 45% de las empresas<\/strong> piensan que deben adquirir los servicios de un centro de datos, sin embargo, hay una <strong>barrera cultural<\/strong> que evita que adopten por completo esta tecnolog\u00eda.<\/h5>\n<h5><\/h5>\n<h5>De acuerdo con <strong>Gabriel Mu\u00f1oz<\/strong>, Director de Estrategia de TI de Alestra, el tema de la seguridad es lo m\u00e1s importante para los negocios, pues aunque M\u00e9xico es un mercado grande, a\u00fan est\u00e1 en proceso de maduraci\u00f3n. <strong>El 70% de los clientes est\u00e1n preocupados por la seguridad<\/strong>.<\/h5>\n<h5><\/h5>\n<h5>Y es que, solo las grandes empresas de nuestro pa\u00eds son las que poco a poco se deciden a contratar los servicios en los centros de datos.<\/h5>\n<h5><\/h5>\n<h5>Hasta el momento, las <strong>industrias<\/strong> que registran mayor demanda para utilizar los centros de datos son: la manufactura, log\u00edstica, salud, educaci\u00f3n, y el sector financiero.<\/h5>\n<h5><\/h5>\n<h5>El cambio que sufren las industrias hoy en d\u00eda, indican que los servicios de TI ayudan a <strong>transformar los negocios<\/strong> en muchos sentidos. No solamente se trata de almacenar informaci\u00f3n, tambi\u00e9n hay todo un desarrollo de aplicaciones, y hasta tercerizaci\u00f3n de servicios en la nube.<\/h5>\n<h5><\/h5>\n<h5>La demanda de servicios a la que se ha enfocado el mercado mexicano, est\u00e1 en la coubicaci\u00f3n, servicio administrado y los servicios en la nube.<\/h5>\n<h5><\/h5>\n<hr \/>\n<h5><\/h5>\n<p>fuente:\u00a0dineroenimagen.com<\/p>\n<div class=\"pvc_clear\"><\/div>\n<p id=\"pvc_stats_5680\" class=\"pvc_stats all  \" data-element-id=\"5680\" style=\"\"><i class=\"pvc-stats-icon medium\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/la-uno.com\/blog\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p>\n<div class=\"pvc_clear\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>\u00bfAlguna vez te has preguntado a d\u00f3nde va toda esa informaci\u00f3n que guardas en la nube?, es decir, la \u201cnube\u201d es s\u00f3lo una expresi\u00f3n, la realidad es que hay un lugar f\u00edsico en el que las empresas o personas,\u00a0guardan toda la informaci\u00f3n\u00a0que no pueden almacenar en dispositivos. A continuaci\u00f3n, te presentamos\u00a0cinco cosas que no sabes&hellip;<\/p>\n<div class=\"pvc_clear\"><\/div>\n<p id=\"pvc_stats_5680\" class=\"pvc_stats all  \" data-element-id=\"5680\" style=\"\"><i class=\"pvc-stats-icon medium\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/la-uno.com\/blog\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p>\n<div class=\"pvc_clear\"><\/div>\n","protected":false},"author":1,"featured_media":5681,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[191,182,37,179],"tags":[],"class_list":["post-5680","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-almacenamiento","category-drive","category-seguridad","category-servidores"],"a3_pvc":{"activated":true,"total_views":3713,"today_views":0},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/la-uno.com\/blog\/wp-content\/uploads\/2014\/12\/dc.jpg","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p529Uq-1tC","jetpack-related-posts":[{"id":5384,"url":"https:\/\/la-uno.com\/blog\/2015\/01\/07\/herramientas-de-respaldo-en-linea\/","url_meta":{"origin":5680,"position":0},"title":"Herramientas de respaldo en linea","author":"marco","date":"January 7, 2015","format":false,"excerpt":"Todos tenemos datos importantes y todos queremos conservarlos el mayor tiempo posible, el problema es que no todos hacemos lo necesario para conservarlos; muchas veces por desidia, otras por ignorancia, pero aqu\u00ed te vamos a ayudar a respaldar eso que es importante para ti de la forma mas segura: En\u2026","rel":"","context":"In &quot;Internet&quot;","block_context":{"text":"Internet","link":"https:\/\/la-uno.com\/blog\/category\/internet\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/la-uno.com\/blog\/wp-content\/uploads\/2015\/01\/dorpboxdrive.png?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":6072,"url":"https:\/\/la-uno.com\/blog\/2014\/12\/05\/los-megaservidores-de-amazon-el-negocio-poco-conocido-de-la-tienda-online\/","url_meta":{"origin":5680,"position":1},"title":"Los megaservidores de Amazon, el negocio poco conocido de la tienda online","author":"marco","date":"December 5, 2014","format":false,"excerpt":"La lista de productos de Amazon en internet parece interminable y a\u00fan as\u00ed contin\u00faa creciendo. Por algo se ha ganado el apodo de \"la tienda de todo\". Y sin embargo, un brazo menos conocido de esta misma compa\u00f1\u00eda ofrece bienes menos tangibles pero quiz\u00e1s m\u00e1s importantes para el futuro de\u2026","rel":"","context":"In &quot;almacenamiento&quot;","block_context":{"text":"almacenamiento","link":"https:\/\/la-uno.com\/blog\/category\/almacenamiento\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/la-uno.com\/blog\/wp-content\/uploads\/2014\/12\/amazon-webservices-reception1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/la-uno.com\/blog\/wp-content\/uploads\/2014\/12\/amazon-webservices-reception1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/la-uno.com\/blog\/wp-content\/uploads\/2014\/12\/amazon-webservices-reception1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/la-uno.com\/blog\/wp-content\/uploads\/2014\/12\/amazon-webservices-reception1.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/la-uno.com\/blog\/wp-content\/uploads\/2014\/12\/amazon-webservices-reception1.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/la-uno.com\/blog\/wp-content\/uploads\/2014\/12\/amazon-webservices-reception1.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":8241,"url":"https:\/\/la-uno.com\/blog\/2015\/08\/11\/hackeando-dropbox-google-drive-onedrive-y-otros-sin-necesidad-de-saber-nombre-de-usuario-y-contrasena\/","url_meta":{"origin":5680,"position":2},"title":"Hackeando Dropbox, Google Drive, OneDrive y otros sin necesidad de saber nombre de usuario y contrase\u00f1a.","author":"marco","date":"August 11, 2015","format":false,"excerpt":"\u00a0\u00a0 La compa\u00f1\u00eda Imperva ha mostrado un gran fallo de seguridad en Dropbox, GoogleDrive, OneDrive y otros servicios de almacenamiento en la nube que permite al atacante tener acceso a los archivos e incluso instalar malware sin siquiera tener el nombre de usuario y contrase\u00f1a. El problema de seguridad se\u2026","rel":"","context":"In &quot;Internet&quot;","block_context":{"text":"Internet","link":"https:\/\/la-uno.com\/blog\/category\/internet\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/la-uno.com\/blog\/wp-content\/uploads\/2015\/08\/IMG_0553.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/la-uno.com\/blog\/wp-content\/uploads\/2015\/08\/IMG_0553.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/la-uno.com\/blog\/wp-content\/uploads\/2015\/08\/IMG_0553.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":5395,"url":"https:\/\/la-uno.com\/blog\/2015\/01\/09\/thunderstrike-el-boot-kit-que-apple-no-puede-eliminar\/","url_meta":{"origin":5680,"position":3},"title":"Thunderstrike,  el boot kit que Apple no puede eliminar","author":"marco","date":"January 9, 2015","format":false,"excerpt":"OS X siempre ha sido anunciado como el sistema operativo mas avanzado del mundo, y siendo honestos es en mi opini\u00f3n el mejor, claro, todo depende de para que lo usas y de las herramientas que usas en tu dia a dia, pero siendo un poco mas t\u00e9cnicos OS X\u2026","rel":"","context":"In &quot;Apple&quot;","block_context":{"text":"Apple","link":"https:\/\/la-uno.com\/blog\/category\/apple\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/la-uno.com\/blog\/wp-content\/uploads\/2015\/01\/shutterstock_209983375-680x400.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/la-uno.com\/blog\/wp-content\/uploads\/2015\/01\/shutterstock_209983375-680x400.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/la-uno.com\/blog\/wp-content\/uploads\/2015\/01\/shutterstock_209983375-680x400.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":5589,"url":"https:\/\/la-uno.com\/blog\/2014\/10\/13\/ventajas-del-alojamiento-web-compartido\/","url_meta":{"origin":5680,"position":4},"title":"Ventajas del alojamiento web compartido","author":"marco","date":"October 13, 2014","format":false,"excerpt":"Alojamiento web, o web hosting en ingl\u00e9s, es el servicio que provee a los usuarios de Internet el poder almacenar datos como fotos, v\u00eddeos o cualquier contenido accesible v\u00eda web, llam\u00e1ndose as\u00ed a partir del alojamiento en hoteles donde uno ocupa una habitaci\u00f3n o lugar en especifico, de ah\u00ed el\u2026","rel":"","context":"In &quot;Internet&quot;","block_context":{"text":"Internet","link":"https:\/\/la-uno.com\/blog\/category\/internet\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/la-uno.com\/blog\/wp-content\/uploads\/2014\/10\/hostingsd.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/la-uno.com\/blog\/wp-content\/uploads\/2014\/10\/hostingsd.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/la-uno.com\/blog\/wp-content\/uploads\/2014\/10\/hostingsd.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/la-uno.com\/blog\/wp-content\/uploads\/2014\/10\/hostingsd.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":11082,"url":"https:\/\/la-uno.com\/blog\/2018\/04\/10\/steve-wozniak-dejara-de-usar-facebook-eres-el-producto\/","url_meta":{"origin":5680,"position":5},"title":"Steve Wozniak dejar\u00e1 de usar Facebook &#8220;Eres el producto&#8221;","author":"marco","date":"April 10, 2018","format":false,"excerpt":"No es muy dif\u00edcil de entender, si alguien no te cobra por un servicio o producto.. es porque tu eres el producto, o ustedes creen que les dan las muestras \"gratis\" en el super solo por compartir?, aunque hay que tomar las cosas con un poco de sal. \u201cLos usuarios\u2026","rel":"","context":"In &quot;Facebook&quot;","block_context":{"text":"Facebook","link":"https:\/\/la-uno.com\/blog\/category\/facebook\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/la-uno.com\/blog\/wp-content\/uploads\/2018\/04\/MW-GG976_woz_ZG_20180409054941.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/la-uno.com\/blog\/wp-content\/uploads\/2018\/04\/MW-GG976_woz_ZG_20180409054941.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/la-uno.com\/blog\/wp-content\/uploads\/2018\/04\/MW-GG976_woz_ZG_20180409054941.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/la-uno.com\/blog\/wp-content\/uploads\/2018\/04\/MW-GG976_woz_ZG_20180409054941.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/la-uno.com\/blog\/wp-content\/uploads\/2018\/04\/MW-GG976_woz_ZG_20180409054941.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/la-uno.com\/blog\/wp-json\/wp\/v2\/posts\/5680","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/la-uno.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/la-uno.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/la-uno.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/la-uno.com\/blog\/wp-json\/wp\/v2\/comments?post=5680"}],"version-history":[{"count":1,"href":"https:\/\/la-uno.com\/blog\/wp-json\/wp\/v2\/posts\/5680\/revisions"}],"predecessor-version":[{"id":5682,"href":"https:\/\/la-uno.com\/blog\/wp-json\/wp\/v2\/posts\/5680\/revisions\/5682"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/la-uno.com\/blog\/wp-json\/wp\/v2\/media\/5681"}],"wp:attachment":[{"href":"https:\/\/la-uno.com\/blog\/wp-json\/wp\/v2\/media?parent=5680"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/la-uno.com\/blog\/wp-json\/wp\/v2\/categories?post=5680"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/la-uno.com\/blog\/wp-json\/wp\/v2\/tags?post=5680"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}