{"id":54,"date":"2014-09-08T12:56:36","date_gmt":"2014-09-08T18:56:36","guid":{"rendered":"http:\/\/la-uno.com\/blog\/?p=54"},"modified":"2015-02-18T14:46:22","modified_gmt":"2015-02-18T20:46:22","slug":"nuevo-blog","status":"publish","type":"post","link":"https:\/\/la-uno.com\/blog\/2014\/09\/08\/nuevo-blog\/","title":{"rendered":"Nuevo Blog"},"content":{"rendered":"<p><a href=\"http:\/\/la-uno.com\/blog\/wp-content\/uploads\/2014\/09\/Nuevo.gif\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-56 size-full\" src=\"http:\/\/la-uno.com\/blog\/wp-content\/uploads\/2014\/09\/Nuevo.gif\" alt=\"Nuevo\" width=\"268\" height=\"246\" \/><\/a><\/p>\n<p>Chicos, les tengo buenas noticias!!! (en voz del Dr.\u00a0Farnsworth).<\/p>\n<p>Este blog ahora corre con un nuevo software, desafortunadamente no hay forma f\u00e1cil de migrar todo el titipuchal de posts del blog anterior a este as\u00ed que vamos a empezar de nuevo.<\/p>\n<p>Esto no quiere decir que los posts\/im\u00e1genes anteriores ya no vayan a estar disponibles, nada de eso, de hecho ahi van a estar hasta que se nos acabe el hospedaje o se acabe el internet, lo primero que pase, sin embargo, ahora al entrar en http:\/\/www.la-uno.com la pagina que ver\u00e1n ser\u00e1 esta en lugar del blog anterior.<\/p>\n<p>Si aun as\u00ed quieren echarse un clavado en el blog anterior entonces ahora tendr\u00e1n que picarle aqu\u00ed: <a href=\"http:\/\/www.la-uno.com\/html\/\" target=\"_blank\">http:\/\/www.la-uno.com\/html\/<\/a><\/p>\n<div class=\"pvc_clear\"><\/div>\n<p id=\"pvc_stats_54\" class=\"pvc_stats all  \" data-element-id=\"54\" style=\"\"><i class=\"pvc-stats-icon medium\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/la-uno.com\/blog\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p>\n<div class=\"pvc_clear\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Chicos, les tengo buenas noticias!!! (en voz del Dr.\u00a0Farnsworth). Este blog ahora corre con un nuevo software, desafortunadamente no hay forma f\u00e1cil de migrar todo el titipuchal de posts del blog anterior a este as\u00ed que vamos a empezar de nuevo. Esto no quiere decir que los posts\/im\u00e1genes anteriores ya no vayan a estar disponibles,&hellip;<\/p>\n<div class=\"pvc_clear\"><\/div>\n<p id=\"pvc_stats_54\" class=\"pvc_stats all  \" data-element-id=\"54\" style=\"\"><i class=\"pvc-stats-icon medium\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/la-uno.com\/blog\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p>\n<div class=\"pvc_clear\"><\/div>\n","protected":false},"author":1,"featured_media":56,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[36,1],"tags":[],"class_list":["post-54","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-featured","category-uncategorized"],"a3_pvc":{"activated":true,"total_views":6464,"today_views":0},"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p529Uq-S","jetpack-related-posts":[{"id":5066,"url":"https:\/\/la-uno.com\/blog\/2014\/10\/03\/asi-es-el-nuevo-nexus-6\/","url_meta":{"origin":54,"position":0},"title":"Asi es el nuevo Nexus 6","author":"marco","date":"October 3, 2014","format":false,"excerpt":"El canal de Youtube Canoopsy ha creado un render del nuevo Motorola Nexus 6, a primera impresi\u00f3n es un telefono grande ya que cuenta con una pantalla de 5.9\", a mi gusto esto est\u00e1 llegando al punto de ser rid\u00edculo, cierto, entre la pantalla mas grande es mas grande se\u2026","rel":"","context":"In &quot;Google&quot;","block_context":{"text":"Google","link":"https:\/\/la-uno.com\/blog\/category\/google-2\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/la-uno.com\/blog\/wp-content\/uploads\/2014\/10\/nexus-6-video.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/la-uno.com\/blog\/wp-content\/uploads\/2014\/10\/nexus-6-video.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/la-uno.com\/blog\/wp-content\/uploads\/2014\/10\/nexus-6-video.jpeg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":8536,"url":"https:\/\/la-uno.com\/blog\/2015\/10\/27\/el-nuevo-apple-tv-ya-esta-a-la-venta-en-mexico\/","url_meta":{"origin":54,"position":1},"title":"El nuevo Apple TV ya est\u00e1 a la venta en M\u00e9xico","author":"marco","date":"October 27, 2015","format":false,"excerpt":"El \u00a0Apple TV 4\u00a0que fue presentado en septiembre ya est\u00e1 a la venta en la tienda en l\u00ednea de Apple y los distribuidores habituales en M\u00e9xico. El Apple TV no tiene muchos cambios por fuera, mas bien por dentro y que ahora incluye un microprocesador mucho mas poderoso, un A8\u2026","rel":"","context":"In &quot;Apple&quot;","block_context":{"text":"Apple","link":"https:\/\/la-uno.com\/blog\/category\/apple\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/la-uno.com\/blog\/wp-content\/uploads\/2015\/10\/apple-tv-mando-1.gif?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/la-uno.com\/blog\/wp-content\/uploads\/2015\/10\/apple-tv-mando-1.gif?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/la-uno.com\/blog\/wp-content\/uploads\/2015\/10\/apple-tv-mando-1.gif?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":9900,"url":"https:\/\/la-uno.com\/blog\/2017\/02\/27\/asi-se-ve-el-nuevo-apple-campus-ahora\/","url_meta":{"origin":54,"position":2},"title":"As\u00ed se ve el nuevo Apple Campus ahora","author":"marco","date":"February 27, 2017","format":false,"excerpt":"Poco a poco va tomando mas forma el nuevo campos de Apple donde todos sus trabajadores se mudar\u00e1n, y me refiero a todos los que trabajan en dise\u00f1o y desarrollo, administrativos etc. El campus tiene capacidad para 12,000 personas, todo un pueblo. Contar\u00e1 con Gimnasio, cafeteria, Apple Store y zonas\u2026","rel":"","context":"In &quot;Apple&quot;","block_context":{"text":"Apple","link":"https:\/\/la-uno.com\/blog\/category\/apple\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/la-uno.com\/blog\/wp-content\/uploads\/2017\/02\/maxresdefault-2.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/la-uno.com\/blog\/wp-content\/uploads\/2017\/02\/maxresdefault-2.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/la-uno.com\/blog\/wp-content\/uploads\/2017\/02\/maxresdefault-2.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/la-uno.com\/blog\/wp-content\/uploads\/2017\/02\/maxresdefault-2.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/la-uno.com\/blog\/wp-content\/uploads\/2017\/02\/maxresdefault-2.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":10631,"url":"https:\/\/la-uno.com\/blog\/2017\/10\/19\/ubuntu-17-10-disponible-para-descarga\/","url_meta":{"origin":54,"position":3},"title":"Ubuntu 17.10 disponible para descarga!","author":"marco","date":"October 19, 2017","format":false,"excerpt":"Como cada 6 meses, una nueva versi\u00f3n de Ubuntu ha llegado, pero esta es algo especial, veamos por que. Con esta nueva versi\u00f3n de Ubuntu, Canonical le ha dicho adi\u00f3s al entra\u00f1able Unity, que ha quedado relegado en favor del escritorio de GNOME que es de nuevo el ambiente de\u2026","rel":"","context":"In &quot;Linux&quot;","block_context":{"text":"Linux","link":"https:\/\/la-uno.com\/blog\/category\/linux\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/la-uno.com\/blog\/wp-content\/uploads\/2017\/10\/dock-750x340.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/la-uno.com\/blog\/wp-content\/uploads\/2017\/10\/dock-750x340.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/la-uno.com\/blog\/wp-content\/uploads\/2017\/10\/dock-750x340.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/la-uno.com\/blog\/wp-content\/uploads\/2017\/10\/dock-750x340.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":7739,"url":"https:\/\/la-uno.com\/blog\/2015\/05\/14\/el-nuevo-moto-x-podria-tener-una-camara-de-16mp-y-video-4k\/","url_meta":{"origin":54,"position":4},"title":"El nuevo Moto X podria tener una c\u00e1mara de 16MP y video 4K","author":"marco","date":"May 14, 2015","format":"image","excerpt":"Se han filtrado las especificaciones del pr\u00f3ximo Moto X y sugieren que Motorola va a arreglar uno de las mas grandes quejas de sus fans en el modelo actual: La c\u00e1mara. El nuevo dispositivo tendr\u00e1 una camara trasera de 16MP con todas las caracter\u00edsticas que se esperan de un dispositivo\u2026","rel":"","context":"In &quot;Android&quot;","block_context":{"text":"Android","link":"https:\/\/la-uno.com\/blog\/category\/mobile\/android\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/la-uno.com\/blog\/wp-content\/uploads\/2015\/05\/Moto-X-2014-back-940x640.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/la-uno.com\/blog\/wp-content\/uploads\/2015\/05\/Moto-X-2014-back-940x640.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/la-uno.com\/blog\/wp-content\/uploads\/2015\/05\/Moto-X-2014-back-940x640.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/la-uno.com\/blog\/wp-content\/uploads\/2015\/05\/Moto-X-2014-back-940x640.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":7678,"url":"https:\/\/la-uno.com\/blog\/2015\/05\/05\/grooveshark-esta-de-vuelta\/","url_meta":{"origin":54,"position":5},"title":"Grooveshark est\u00e1 de vuelta","author":"Uzziel","date":"May 5, 2015","format":false,"excerpt":"As\u00ed\u00a0como lo lees, un nuevo\u00a0Grooveshark est\u00e1 funcionando ahora, no como el de antes\u00a0pero funciona, eso gracias a un usuario que\u00a0se hace llamar Shark, eso es lo que dicen en BGR: Empec\u00e9 a hacer copias de seguridad de todo el contenido de la p\u00e1gina web cuando empec\u00e9 a sospechar que la\u2026","rel":"","context":"In &quot;Musica&quot;","block_context":{"text":"Musica","link":"https:\/\/la-uno.com\/blog\/category\/musica\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/la-uno.com\/blog\/wp-content\/uploads\/2015\/05\/grooveshark_logo.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/la-uno.com\/blog\/wp-content\/uploads\/2015\/05\/grooveshark_logo.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/la-uno.com\/blog\/wp-content\/uploads\/2015\/05\/grooveshark_logo.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]}],"jetpack_featured_media_url":"https:\/\/la-uno.com\/blog\/wp-content\/uploads\/2014\/09\/Nuevo.gif","_links":{"self":[{"href":"https:\/\/la-uno.com\/blog\/wp-json\/wp\/v2\/posts\/54","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/la-uno.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/la-uno.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/la-uno.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/la-uno.com\/blog\/wp-json\/wp\/v2\/comments?post=54"}],"version-history":[{"count":2,"href":"https:\/\/la-uno.com\/blog\/wp-json\/wp\/v2\/posts\/54\/revisions"}],"predecessor-version":[{"id":57,"href":"https:\/\/la-uno.com\/blog\/wp-json\/wp\/v2\/posts\/54\/revisions\/57"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/la-uno.com\/blog\/wp-json\/wp\/v2\/media\/56"}],"wp:attachment":[{"href":"https:\/\/la-uno.com\/blog\/wp-json\/wp\/v2\/media?parent=54"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/la-uno.com\/blog\/wp-json\/wp\/v2\/categories?post=54"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/la-uno.com\/blog\/wp-json\/wp\/v2\/tags?post=54"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}