{"id":5295,"date":"2014-12-10T20:02:25","date_gmt":"2014-12-11T02:02:25","guid":{"rendered":"http:\/\/la-uno.com\/blog\/?p=5295"},"modified":"2015-02-18T14:46:15","modified_gmt":"2015-02-18T20:46:15","slug":"la-segunda-beta-de-ios-8-2-ya-esta-en-manos-de-los-desarrolladores","status":"publish","type":"post","link":"https:\/\/la-uno.com\/blog\/2014\/12\/10\/la-segunda-beta-de-ios-8-2-ya-esta-en-manos-de-los-desarrolladores\/","title":{"rendered":"La segunda beta de iOS 8.2 ya est\u00e1 en manos de los desarrolladores"},"content":{"rendered":"<p><a href=\"http:\/\/la-uno.com\/blog\/wp-content\/uploads\/2014\/12\/650_1000_ios-8.2-beta-2.png\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-5296\" src=\"http:\/\/la-uno.com\/blog\/wp-content\/uploads\/2014\/12\/650_1000_ios-8.2-beta-2.png\" alt=\"650_1000_ios-8.2-beta-2\" width=\"640\" height=\"457\" \/><\/a><\/p>\n<p>iOS 8 seguro ser\u00e1 recordado por tener una entrada tan accidentada como ninguna otra liberaci\u00f3n anterior, y aun con las actualizaciones que le han seguido la cosa no se ha calmado, pues Apple acaba de liberar iOS 8.2 Beta 2 para los desarrolladores.<\/p>\n<p>No hay grandes cambios, al parecer solo ha mejorado la sincronizaci\u00f3n con Apple Watch y el desempe\u00f1o al momento de conectar con apps a trav\u00e9s de WatchKit.<\/p>\n<div class=\"pvc_clear\"><\/div>\n<p id=\"pvc_stats_5295\" class=\"pvc_stats all  \" data-element-id=\"5295\" style=\"\"><i class=\"pvc-stats-icon medium\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/la-uno.com\/blog\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p>\n<div class=\"pvc_clear\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>iOS 8 seguro ser\u00e1 recordado por tener una entrada tan accidentada como ninguna otra liberaci\u00f3n anterior, y aun con las actualizaciones que le han seguido la cosa no se ha calmado, pues Apple acaba de liberar iOS 8.2 Beta 2 para los desarrolladores. No hay grandes cambios, al parecer solo ha mejorado la sincronizaci\u00f3n con&hellip;<\/p>\n<div class=\"pvc_clear\"><\/div>\n<p id=\"pvc_stats_5295\" class=\"pvc_stats all  \" data-element-id=\"5295\" style=\"\"><i class=\"pvc-stats-icon medium\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/la-uno.com\/blog\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p>\n<div class=\"pvc_clear\"><\/div>\n","protected":false},"author":1,"featured_media":5174,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[50,56],"tags":[130],"class_list":["post-5295","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-apple","category-ios","tag-ios-8"],"a3_pvc":{"activated":true,"total_views":1199,"today_views":0},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/la-uno.com\/blog\/wp-content\/uploads\/2014\/11\/650_1000_ios8logo.png","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p529Uq-1np","jetpack-related-posts":[{"id":5173,"url":"https:\/\/la-uno.com\/blog\/2014\/11\/04\/apple-lanza-ios-8-1-1-a-los-desarrolladores\/","url_meta":{"origin":5295,"position":0},"title":"Apple lanza iOS 8.1.1 a los desarrolladores","author":"marco","date":"November 4, 2014","format":false,"excerpt":"Apple ha liberado iOS 8.1.1 a los desarrolladores, como su n\u00famero lo indica, comparado con iOS 8.1 (estable) esta es solo una actualizaci\u00f3n menor que corresponde a mejoras de rendimiento y estabilidad, se solucionar\u00e1n problemas que algunos usuarios se est\u00e1n encontrando con sus dispositivos, concretamente los usuarios con dispositivos antiguos.\u2026","rel":"","context":"In &quot;Apple&quot;","block_context":{"text":"Apple","link":"https:\/\/la-uno.com\/blog\/category\/apple\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/la-uno.com\/blog\/wp-content\/uploads\/2014\/09\/IOS_8_logo.png?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":9429,"url":"https:\/\/la-uno.com\/blog\/2016\/08\/15\/apple-libera-ios-10-beta-6-a-desarrolladores-beta-5-a-todo-el-mundo\/","url_meta":{"origin":5295,"position":1},"title":"Apple libera iOS 10 Beta 6 a desarrolladores, Beta 5 a todo el mundo","author":"marco","date":"August 15, 2016","format":false,"excerpt":"Apple ha liberado el dia de hoy la beta 6 de la nueva versi\u00f3n de iOS 10 a los desarrolladores, mientras que al publico en general (suscrito al programa de testers) la beta 5. Si ya cuentas con iOS 10 Beta en tu dispositivo, la actualizaci\u00f3n es tan f\u00e1cil como\u2026","rel":"","context":"In &quot;Apple&quot;","block_context":{"text":"Apple","link":"https:\/\/la-uno.com\/blog\/category\/apple\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/la-uno.com\/blog\/wp-content\/uploads\/2016\/08\/img_3745.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/la-uno.com\/blog\/wp-content\/uploads\/2016\/08\/img_3745.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/la-uno.com\/blog\/wp-content\/uploads\/2016\/08\/img_3745.png?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/la-uno.com\/blog\/wp-content\/uploads\/2016\/08\/img_3745.png?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/la-uno.com\/blog\/wp-content\/uploads\/2016\/08\/img_3745.png?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/la-uno.com\/blog\/wp-content\/uploads\/2016\/08\/img_3745.png?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":11206,"url":"https:\/\/la-uno.com\/blog\/2018\/07\/30\/apple-libera-la-beta-5-de-ios-12-macos-mojave-tvos\/","url_meta":{"origin":5295,"position":2},"title":"Apple libera la beta 5 de iOS 12, macOS Mojave, tvOS","author":"marco","date":"July 30, 2018","format":false,"excerpt":"Apple ha liberado la quinta beta de la pr\u00f3xima actualizaci\u00f3n mayor de los sistemas operativos para sus dispositivos. No hay de momento nada nuevo que destaque en las betas, por lo que se cree que se centran mejoras en rendimiento y estabilidad. La beta est\u00e1 actualmente disponible solo para desarrolladores\u2026","rel":"","context":"In &quot;Apple&quot;","block_context":{"text":"Apple","link":"https:\/\/la-uno.com\/blog\/category\/apple\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/la-uno.com\/blog\/wp-content\/uploads\/2018\/07\/450_1000.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":9907,"url":"https:\/\/la-uno.com\/blog\/2017\/02\/27\/apple-lanza-nuevas-betas-de-ios-macos-y-watchos\/","url_meta":{"origin":5295,"position":3},"title":"Apple lanza nuevas betas de iOS, macOS y watchOS","author":"marco","date":"February 27, 2017","format":false,"excerpt":"Los desarrolladores han recibido tres\u00a0nuevas Betas por parte de Apple, iOS 10.3, watchOS 3.2 y macOS 10.12.4, justo una semana antes de su lanzamiento. Las nuevas Betas de iOS 10.3 beta4 y macOS 10.12.4 beta 4 pueden ser descargadas por desarrolladores registrados directamente desde el portal de Apple, iOS 10.3\u2026","rel":"","context":"In &quot;Apple&quot;","block_context":{"text":"Apple","link":"https:\/\/la-uno.com\/blog\/category\/apple\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/la-uno.com\/blog\/wp-content\/uploads\/2017\/02\/iOS9.3b4-780x521.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/la-uno.com\/blog\/wp-content\/uploads\/2017\/02\/iOS9.3b4-780x521.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/la-uno.com\/blog\/wp-content\/uploads\/2017\/02\/iOS9.3b4-780x521.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/la-uno.com\/blog\/wp-content\/uploads\/2017\/02\/iOS9.3b4-780x521.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":9217,"url":"https:\/\/la-uno.com\/blog\/2016\/07\/07\/las-betas-de-macos-sierra-y-ios-10-son-publicas-ahora\/","url_meta":{"origin":5295,"position":4},"title":"Las betas de macOS Sierra y iOS 10 son publicas ahora","author":"marco","date":"July 7, 2016","format":false,"excerpt":"Los fans de Apple, los aventurados ahora pueden tener una prueba de iOS 10 y de macOS Sierra antes de que se haga p\u00fablico en su versi\u00f3n estable. Apple ha hecho publicas las versiones beta de iOS 10 y macOS Sierra. Justo dos dias despues de la liberaci\u00f3n de iOS\u2026","rel":"","context":"In &quot;Apple&quot;","block_context":{"text":"Apple","link":"https:\/\/la-uno.com\/blog\/category\/apple\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/la-uno.com\/blog\/wp-content\/uploads\/2016\/07\/macOS-Sierra-2.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/la-uno.com\/blog\/wp-content\/uploads\/2016\/07\/macOS-Sierra-2.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/la-uno.com\/blog\/wp-content\/uploads\/2016\/07\/macOS-Sierra-2.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/la-uno.com\/blog\/wp-content\/uploads\/2016\/07\/macOS-Sierra-2.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/la-uno.com\/blog\/wp-content\/uploads\/2016\/07\/macOS-Sierra-2.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/la-uno.com\/blog\/wp-content\/uploads\/2016\/07\/macOS-Sierra-2.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":10419,"url":"https:\/\/la-uno.com\/blog\/2017\/08\/22\/apple-libera-ios-11-developer-beta-7-15a5362a\/","url_meta":{"origin":5295,"position":5},"title":"Apple libera iOS 11 Developer Beta 7 (15A5362a)","author":"marco","date":"August 22, 2017","format":false,"excerpt":"Apple ha hecho publica la s\u00e9ptima Beta de iOS 11 que esta cada vez mas pr\u00f3xima a ser estable y disponible para todo mundo. La Beta publica esta accesible para aquellos usuarios que se inscriban en el programa de pruebas Betas, si bien las betas se liberan primero a los\u2026","rel":"","context":"In &quot;Apple&quot;","block_context":{"text":"Apple","link":"https:\/\/la-uno.com\/blog\/category\/apple\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/la-uno.com\/blog\/wp-content\/uploads\/2017\/08\/ipad-ios-11.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/la-uno.com\/blog\/wp-content\/uploads\/2017\/08\/ipad-ios-11.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/la-uno.com\/blog\/wp-content\/uploads\/2017\/08\/ipad-ios-11.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/la-uno.com\/blog\/wp-content\/uploads\/2017\/08\/ipad-ios-11.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/la-uno.com\/blog\/wp-content\/uploads\/2017\/08\/ipad-ios-11.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/la-uno.com\/blog\/wp-json\/wp\/v2\/posts\/5295","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/la-uno.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/la-uno.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/la-uno.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/la-uno.com\/blog\/wp-json\/wp\/v2\/comments?post=5295"}],"version-history":[{"count":1,"href":"https:\/\/la-uno.com\/blog\/wp-json\/wp\/v2\/posts\/5295\/revisions"}],"predecessor-version":[{"id":5297,"href":"https:\/\/la-uno.com\/blog\/wp-json\/wp\/v2\/posts\/5295\/revisions\/5297"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/la-uno.com\/blog\/wp-json\/wp\/v2\/media\/5174"}],"wp:attachment":[{"href":"https:\/\/la-uno.com\/blog\/wp-json\/wp\/v2\/media?parent=5295"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/la-uno.com\/blog\/wp-json\/wp\/v2\/categories?post=5295"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/la-uno.com\/blog\/wp-json\/wp\/v2\/tags?post=5295"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}