{"id":5122,"date":"2014-10-23T12:55:06","date_gmt":"2014-10-23T18:55:06","guid":{"rendered":"http:\/\/la-uno.com\/blog\/?p=5122"},"modified":"2015-02-18T14:46:18","modified_gmt":"2015-02-18T20:46:18","slug":"google-confirma-lollipop-para-el-3-de-noviembre","status":"publish","type":"post","link":"https:\/\/la-uno.com\/blog\/2014\/10\/23\/google-confirma-lollipop-para-el-3-de-noviembre\/","title":{"rendered":"Google confirma: Lollipop para el 3 de Noviembre"},"content":{"rendered":"<p><a href=\"http:\/\/la-uno.com\/blog\/index.php\/2014\/10\/23\/google-confirma-lollipop-para-el-3-de-noviembre\/tumblr_ndmup3kw2q1rzedoio1_500-300x300\/#main\" rel=\"attachment wp-att-5123\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-5123 size-full\" src=\"http:\/\/la-uno.com\/blog\/wp-content\/uploads\/2014\/10\/tumblr_ndmup3KW2Q1rzedoio1_500-300x300.jpg\" alt=\"tumblr_ndmup3KW2Q1rzedoio1_500-300x300\" width=\"300\" height=\"300\" srcset=\"https:\/\/la-uno.com\/blog\/wp-content\/uploads\/2014\/10\/tumblr_ndmup3KW2Q1rzedoio1_500-300x300.jpg 300w, https:\/\/la-uno.com\/blog\/wp-content\/uploads\/2014\/10\/tumblr_ndmup3KW2Q1rzedoio1_500-300x300-150x150.jpg 150w, https:\/\/la-uno.com\/blog\/wp-content\/uploads\/2014\/10\/tumblr_ndmup3KW2Q1rzedoio1_500-300x300-50x50.jpg 50w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>Hace una semana, Google anunci\u00f3 su ultima versi\u00f3n de Android, llamada Lollipop y acompa\u00f1ada con la presentaci\u00f3n del Nexus 6 y Nexus 9. Como es costumbre la estatua referente a esta versi\u00f3n de Android se ha hecho ver en el campus de Mountain View. Las actualizaciones llegar\u00e1n primero a los Nexus, siendo los primeros en tenerla el Nexus 6, Nexus 9 y Nexus Player, pero tambi\u00e9n llegar\u00e1 al Nexus 5, 4 y nexus 7 de 2013 y 2012.<\/p>\n<p>Google envi\u00f3 tambi\u00e9n un mensaje indicando que el 3 de Noviembre estar\u00e1 disponible el nexus 9 y avis\u00f3 a los desarrolladores que ser\u00e1 un buen momento para publicar apps actualizadas en la Google Play,\u00a0previendo que los desarrolladores prueben sus apps en Lollipop y corrijan errores antes de llegar a la Google Play.<\/p>\n<p>El mejaje dice:<\/p>\n<blockquote><p>El 3 de Noviembre, el Nexus 9 estar\u00e1 disponible para los consumidores y correr\u00e1 Android 5.0. Asi que es un buen momento de publicar en la Google Play, una vez que hayan actualizado sus apps. Incluso si sus apps tienen como objetivo versiones anteriores de Android, t\u00f3mese un poco de tiempo para probarlo en las im\u00e1genes de sistema de Android 5.0 y publique cualquier actualizaci\u00f3n necesaria previendo la liberaci\u00f3n de Android 5.0.<\/p><\/blockquote>\n<p>&nbsp;<\/p>\n<div class=\"pvc_clear\"><\/div>\n<p id=\"pvc_stats_5122\" class=\"pvc_stats all  \" data-element-id=\"5122\" style=\"\"><i class=\"pvc-stats-icon medium\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/la-uno.com\/blog\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p>\n<div class=\"pvc_clear\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Hace una semana, Google anunci\u00f3 su ultima versi\u00f3n de Android, llamada Lollipop y acompa\u00f1ada con la presentaci\u00f3n del Nexus 6 y Nexus 9. Como es costumbre la estatua referente a esta versi\u00f3n de Android se ha hecho ver en el campus de Mountain View. Las actualizaciones llegar\u00e1n primero a los Nexus, siendo los primeros en&hellip;<\/p>\n<div class=\"pvc_clear\"><\/div>\n<p id=\"pvc_stats_5122\" class=\"pvc_stats all  \" data-element-id=\"5122\" style=\"\"><i class=\"pvc-stats-icon medium\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/la-uno.com\/blog\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p>\n<div class=\"pvc_clear\"><\/div>\n","protected":false},"author":1,"featured_media":5123,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[45,44],"tags":[93],"class_list":["post-5122","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-android","category-mobile","tag-lollipop"],"a3_pvc":{"activated":true,"total_views":2685,"today_views":0},"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p529Uq-1kC","jetpack-related-posts":[{"id":5084,"url":"https:\/\/la-uno.com\/blog\/2014\/10\/18\/android-5-0-lollipop-pronto-para-el-nexus-5-nexus-4-moto-g-moto-e-moto-x-y-otros\/","url_meta":{"origin":5122,"position":0},"title":"Android 5.0 &#8220;Lollipop&#8221; pronto para el Nexus 5, Nexus 4, Moto G, Moto E, Moto X y otros","author":"marco","date":"October 18, 2014","format":false,"excerpt":"El pasado mi\u00e9rcoles Google introdujo el nuevo Nexus (Nexus 6) y su tablet (Nexus 9), aprovechando hizo el anuncio de Android 5.0 \"Lollipop\". La compa\u00f1\u00eda tambi\u00e9n tom\u00f3 por sorpresa al mundo al lanzar el primer dispositivo para TV, el Nexus Player. El gigante de las b\u00fasquedas confirm\u00f3 que Android 5.0\u2026","rel":"","context":"In &quot;Android&quot;","block_context":{"text":"Android","link":"https:\/\/la-uno.com\/blog\/category\/mobile\/android\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/la-uno.com\/blog\/wp-content\/uploads\/2014\/10\/android_lollipop_generic.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/la-uno.com\/blog\/wp-content\/uploads\/2014\/10\/android_lollipop_generic.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/la-uno.com\/blog\/wp-content\/uploads\/2014\/10\/android_lollipop_generic.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":8902,"url":"https:\/\/la-uno.com\/blog\/2016\/03\/17\/tu-nexus-5-podria-llegar-a-actualizarse-a-android-n-al-final-de-cuentas\/","url_meta":{"origin":5122,"position":1},"title":"Tu Nexus 5 podr\u00eda llegar a actualizarse a Android N al final de cuentas.","author":"marco","date":"March 17, 2016","format":false,"excerpt":"La vista previa de la siguiente versi\u00f3n de Android \"N\" no est\u00e1 disponible para el Nexus 5, dejando a algunos con la idea de que s\u00f3lo tendr\u00e1 soporte para marshmallow, pero hay todav\u00eda un hilo de esperanza. En los repositorios de Google se muestra que Google ha trabajando con Android\u2026","rel":"","context":"In &quot;Android&quot;","block_context":{"text":"Android","link":"https:\/\/la-uno.com\/blog\/category\/mobile\/android\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/la-uno.com\/blog\/wp-content\/uploads\/2016\/03\/Nexus-5-Android-N.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/la-uno.com\/blog\/wp-content\/uploads\/2016\/03\/Nexus-5-Android-N.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/la-uno.com\/blog\/wp-content\/uploads\/2016\/03\/Nexus-5-Android-N.png?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":8060,"url":"https:\/\/la-uno.com\/blog\/2015\/06\/29\/un-nuevo-y-mejorado-nexus-5-para-android-m\/","url_meta":{"origin":5122,"position":2},"title":"Un nuevo y mejorado Nexus 5 para Android M","author":"marco","date":"June 29, 2015","format":false,"excerpt":"Corren los rumores de que Google va a lanzar una nueva versi\u00f3n del Nexus 5 junto con la actualizaci\u00f3n de Android M este invierno. El dispositivo ser\u00e1 hecho por LG y Google espera con esto revertir las bajas ventas que ha tenido en los Nexus este a\u00f1o. El Nexus 5\u2026","rel":"","context":"In &quot;Android&quot;","block_context":{"text":"Android","link":"https:\/\/la-uno.com\/blog\/category\/mobile\/android\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/la-uno.com\/blog\/wp-content\/uploads\/2015\/06\/Nexus-5-1-940x549.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/la-uno.com\/blog\/wp-content\/uploads\/2015\/06\/Nexus-5-1-940x549.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/la-uno.com\/blog\/wp-content\/uploads\/2015\/06\/Nexus-5-1-940x549.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/la-uno.com\/blog\/wp-content\/uploads\/2015\/06\/Nexus-5-1-940x549.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":5287,"url":"https:\/\/la-uno.com\/blog\/2014\/12\/08\/el-nexus-6-llega-a-mexico\/","url_meta":{"origin":5122,"position":3},"title":"El Nexus 6 llega a M\u00e9xico","author":"marco","date":"December 8, 2014","format":false,"excerpt":"As\u00ed es, ya es posible comprar el Nexus 6 en M\u00e9xico y no necesariamente a trav\u00e9s de Telcel, mas bien desde la p\u00e1gina de Motorola\u00a0con un precio de entrada de $9,999.00 desbloqueado listo para ser usado con cualquier operadora. Asi como en el sitio de Motorola, tambi\u00e9n ser\u00e1 posible adquirir\u2026","rel":"","context":"In &quot;Android&quot;","block_context":{"text":"Android","link":"https:\/\/la-uno.com\/blog\/category\/mobile\/android\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/la-uno.com\/blog\/wp-content\/uploads\/2014\/12\/nexus-6.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/la-uno.com\/blog\/wp-content\/uploads\/2014\/12\/nexus-6.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/la-uno.com\/blog\/wp-content\/uploads\/2014\/12\/nexus-6.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/la-uno.com\/blog\/wp-content\/uploads\/2014\/12\/nexus-6.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":5182,"url":"https:\/\/la-uno.com\/blog\/2014\/11\/05\/liberado-el-codigo-fuente-de-android-5-0\/","url_meta":{"origin":5122,"position":4},"title":"Liberado el c\u00f3digo fuente de Android 5.0","author":"marco","date":"November 5, 2014","format":false,"excerpt":"Despu\u00e9s de varias horas Google ha puesto a disposici\u00f3n las fuentes de Android 5.0 Lollipop en su repositorio Git. Sorprendentemente hay dos versiones disponibles: 5.0.0_r1 para el Nexus 9 y 5.0.0_r2 para el Nexus Player. Alisten sus teminales porque hay que sincronizar el c\u00f3digo y empezar a compilar. Google inici\u00f3\u2026","rel":"","context":"In &quot;Android&quot;","block_context":{"text":"Android","link":"https:\/\/la-uno.com\/blog\/category\/mobile\/android\/"},"img":{"alt_text":"android_lollipop_generic","src":"https:\/\/i0.wp.com\/la-uno.com\/blog\/wp-content\/uploads\/2014\/10\/android_lollipop_generic.jpg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/la-uno.com\/blog\/wp-content\/uploads\/2014\/10\/android_lollipop_generic.jpg?resize=350%2C200 1x, https:\/\/i0.wp.com\/la-uno.com\/blog\/wp-content\/uploads\/2014\/10\/android_lollipop_generic.jpg?resize=525%2C300 1.5x"},"classes":[]},{"id":5157,"url":"https:\/\/la-uno.com\/blog\/2014\/11\/04\/android-l-es-por-lockdown\/","url_meta":{"origin":5122,"position":5},"title":"Android L es por Lockdown","author":"marco","date":"November 4, 2014","format":false,"excerpt":"root es sin duda alguna, el santo grial del mundo de Android (y de los Unix). Tener acceso al usuario root\u00a0nos permite realizar tareas en el dispositivo que normalmente no deber\u00edamos poder hacer, esa es una de las principales razones por la que Android ha ganado popularidad, no solo en\u2026","rel":"","context":"In &quot;Android&quot;","block_context":{"text":"Android","link":"https:\/\/la-uno.com\/blog\/category\/mobile\/android\/"},"img":{"alt_text":"lockdown-230x300","src":"https:\/\/i0.wp.com\/la-uno.com\/blog\/wp-content\/uploads\/2014\/11\/lockdown-230x300.png?resize=350%2C200","width":350,"height":200},"classes":[]}],"jetpack_featured_media_url":"https:\/\/la-uno.com\/blog\/wp-content\/uploads\/2014\/10\/tumblr_ndmup3KW2Q1rzedoio1_500-300x300.jpg","_links":{"self":[{"href":"https:\/\/la-uno.com\/blog\/wp-json\/wp\/v2\/posts\/5122","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/la-uno.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/la-uno.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/la-uno.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/la-uno.com\/blog\/wp-json\/wp\/v2\/comments?post=5122"}],"version-history":[{"count":3,"href":"https:\/\/la-uno.com\/blog\/wp-json\/wp\/v2\/posts\/5122\/revisions"}],"predecessor-version":[{"id":5126,"href":"https:\/\/la-uno.com\/blog\/wp-json\/wp\/v2\/posts\/5122\/revisions\/5126"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/la-uno.com\/blog\/wp-json\/wp\/v2\/media\/5123"}],"wp:attachment":[{"href":"https:\/\/la-uno.com\/blog\/wp-json\/wp\/v2\/media?parent=5122"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/la-uno.com\/blog\/wp-json\/wp\/v2\/categories?post=5122"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/la-uno.com\/blog\/wp-json\/wp\/v2\/tags?post=5122"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}